{"id":8,"date":"2025-02-24T19:19:53","date_gmt":"2025-02-24T19:19:53","guid":{"rendered":"https:\/\/motelpedromontt.cl\/?page_id=8"},"modified":"2025-03-18T17:48:17","modified_gmt":"2025-03-18T17:48:17","slug":"inicio","status":"publish","type":"page","link":"https:\/\/motelpedromontt.cl\/","title":{"rendered":"inicio"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbHeader\u00bb module_id=\u00bbinicio\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#FAF5EF\u00bb overflow-x=\u00bbhidden\u00bb overflow-y=\u00bbhidden\u00bb custom_padding=\u00bb0px||||false|false\u00bb locked=\u00bboff\u00bb collapsed=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb3_5,2_5&#8243; _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb||||false|false\u00bb custom_padding=\u00bb0px||2px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb3_5&#8243; _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb10%||8vw||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbc16985e1-e0d6-4022-964d-e2bfc04fa633&#8243; header_font=\u00bbManrope|700||on|||||\u00bb header_text_color=\u00bb#000000&#8243; header_font_size=\u00bb51px\u00bb header_letter_spacing=\u00bb0.05em\u00bb header_line_height=\u00bb1.2em\u00bb header_font_size_tablet=\u00bb40px\u00bb header_font_size_phone=\u00bb24px\u00bb header_font_size_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h1>Descubra MOTEL PEDRO MONTT<\/h1>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb1f09816e-184e-4ce5-a4cf-b39c52c423ca\u00bb text_font=\u00bbOpen Sans||||||||\u00bb text_text_color=\u00bb#666666&#8243; text_font_size=\u00bb25px\u00bb text_line_height=\u00bb1.8em\u00bb link_text_color=\u00bb#666666&#8243; text_font_size_tablet=\u00bb15px\u00bb text_font_size_phone=\u00bb14px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb header_font_size_tablet=\u00bb55px\u00bb header_font_size_last_edited=\u00bboff|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Abierto las 24 horas todos los d\u00edas del a\u00f1o<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb2_5&#8243; _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/motelpedromontt.cl\/wp-content\/uploads\/2025\/02\/S7A5228.jpg\u00bb title_text=\u00bb_S7A5228&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb max_width_last_edited=\u00bboff|tablet\u00bb custom_margin=\u00bb|-20vw|-16vw||false|false\u00bb custom_margin_tablet=\u00bb|0vw|0vw||false|false\u00bb custom_margin_phone=\u00bb||||false|false\u00bb custom_margin_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; use_custom_gutter=\u00bbon\u00bb gutter_width=\u00bb1&#8243; make_equal=\u00bbon\u00bb custom_padding_last_edited=\u00bboff|desktop\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#FAF5EF\u00bb transform_scale_last_edited=\u00bboff|desktop\u00bb transform_translate_tablet=\u00bb0px|80%\u00bb transform_translate_phone=\u00bb0px|0%\u00bb transform_translate_last_edited=\u00bboff|desktop\u00bb transform_rotate_last_edited=\u00bboff|desktop\u00bb transform_skew_last_edited=\u00bboff|desktop\u00bb transform_origin_last_edited=\u00bboff|desktop\u00bb transform_styles_last_edited=\u00bboff|desktop\u00bb z_index=\u00bb10&#8243; width_last_edited=\u00bboff|desktop\u00bb custom_margin=\u00bb||2vw||false|false\u00bb custom_margin_tablet=\u00bb||0vw||false|false\u00bb custom_margin_phone=\u00bb||0vw||false|false\u00bb custom_margin_last_edited=\u00bboff|desktop\u00bb custom_padding=\u00bb20px|10px|20px|10px|true|true\u00bb custom_padding_tablet=\u00bb30px|30px|30px|30px|true|true\u00bb custom_padding_phone=\u00bb||||true|true\u00bb box_shadow_style=\u00bbpreset1&#8243; box_shadow_vertical=\u00bb20px\u00bb box_shadow_blur=\u00bb50px\u00bb box_shadow_color=\u00bbrgba(63,22,0,0.2)\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb20px|20px|20px|20px|true|true\u00bb border_color_all=\u00bb#EBE4DD\u00bb border_width_right=\u00bb2px\u00bb border_width_right_tablet=\u00bb0px\u00bb border_width_right_phone=\u00bb0px\u00bb border_width_right_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb title=\u00bbAvenida Pedro Montt 1379, Santiago\u00bb url=\u00bbhttps:\/\/maps.app.goo.gl\/a85rnc1J8aqyJkFr5&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xf3c5;||fa||900&#8243; icon_color=\u00bb#008186&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb24px\u00bb content_max_width=\u00bb100%\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbb62950b2-9f88-417a-a624-825d61ec2a3d\u00bb header_font=\u00bbManrope|700||on|||||\u00bb header_text_color=\u00bb#D37643&#8243; header_font_size=\u00bb14px\u00bb header_letter_spacing=\u00bb1px\u00bb header_line_height=\u00bb1.4em\u00bb animation=\u00bboff\u00bb link_option_url=\u00bbhttps:\/\/maps.app.goo.gl\/a85rnc1J8aqyJkFr5&#8243; locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Cercano a Metro Rondizzoni, Franklin y Autopista Central<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb20px|20px|20px|20px|true|true\u00bb border_color_all=\u00bb#EBE4DD\u00bb border_width_right=\u00bb2px\u00bb border_width_right_tablet=\u00bb0px\u00bb border_width_right_phone=\u00bb0px\u00bb border_width_right_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb title=\u00bb+56 2 33660015&#8243; url=\u00bbtel:+56233660015&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xf879;||fa||900&#8243; icon_color=\u00bb#008186&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb24px\u00bb content_max_width=\u00bb100%\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbb62950b2-9f88-417a-a624-825d61ec2a3d\u00bb header_font=\u00bbManrope|700||on|||||\u00bb header_text_color=\u00bb#D37643&#8243; header_font_size=\u00bb14px\u00bb header_letter_spacing=\u00bb1px\u00bb header_line_height=\u00bb1.4em\u00bb animation=\u00bboff\u00bb link_option_url=\u00bbtel:+56233660015&#8243; locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Tel\u00e9fono Fijo<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb20px|20px|20px|20px|true|true\u00bb border_color_all=\u00bb#EBE4DD\u00bb border_width_right=\u00bb2px\u00bb border_width_right_tablet=\u00bb0px\u00bb border_width_right_phone=\u00bb0px\u00bb border_width_right_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb title=\u00bb+56 9 21703656&#8243; url=\u00bbhttps:\/\/wa.me\/+56921703656&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xf232;||fa||400&#8243; icon_color=\u00bb#008186&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb24px\u00bb content_max_width=\u00bb100%\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbb62950b2-9f88-417a-a624-825d61ec2a3d\u00bb header_font=\u00bbManrope|700||on|||||\u00bb header_text_color=\u00bb#D37643&#8243; header_font_size=\u00bb14px\u00bb header_letter_spacing=\u00bb1px\u00bb header_line_height=\u00bb1.4em\u00bb animation=\u00bboff\u00bb link_option_url=\u00bbhttps:\/\/wa.me\/+56921703656&#8243; locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>WhatsApp<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbAbout\u00bb module_id=\u00bbhabitaciones\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#FAF5EF\u00bb collapsed=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb max_width=\u00bb890px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbb327cbe4-b1d5-4b66-ad37-40c8f2f061ba\u00bb header_2_font=\u00bbManrope|700|||||||\u00bb header_2_text_color=\u00bb#000000&#8243; header_2_font_size=\u00bb48px\u00bb header_2_line_height=\u00bb1.2em\u00bb text_orientation=\u00bbcenter\u00bb header_2_font_size_tablet=\u00bb32px\u00bb header_2_font_size_phone=\u00bb20px\u00bb header_2_font_size_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>Tipos de Habitaciones<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/motelpedromontt.cl\/wp-content\/uploads\/2025\/02\/S7A5272.jpg\u00bb title_text=\u00bb_S7A5272&#8243; align=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb4827deed-2a92-4d97-a22f-f01067ae6873&#8243; header_font=\u00bb||||||||\u00bb header_font_size=\u00bb28px\u00bb header_4_font=\u00bbManrope|700|||||||\u00bb header_4_text_color=\u00bb#000000&#8243; header_4_font_size=\u00bb36px\u00bb header_4_line_height=\u00bb1.4em\u00bb text_orientation=\u00bbcenter\u00bb custom_margin=\u00bb||0px||false|false\u00bb header_4_font_size_tablet=\u00bb16px\u00bb header_4_font_size_phone=\u00bb14px\u00bb header_4_font_size_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4>Cl\u00e1sicas<\/h4>\n<p>[\/et_pb_text][et_pb_button button_url=\u00bbhttps:\/\/motelpedromontt.cl\/index.php\/clasicas\/\u00bb button_text=\u00bbCon\u00f3zcalas\u00bb button_alignment=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbc9fe482c-2e2c-4f8c-9652-7702a242bc65&#8243; custom_button=\u00bbon\u00bb button_text_size=\u00bb14px\u00bb button_text_color=\u00bb#D37643&#8243; button_bg_color=\u00bbRGBA(255,255,255,0)\u00bb button_border_color=\u00bb#D37643&#8243; button_border_radius=\u00bb0px\u00bb button_font=\u00bbInter|700||on|||||\u00bb custom_padding=\u00bb16px|24px|16px|24px|true|true\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb custom_padding_tablet=\u00bb30px||||false|false\u00bb custom_padding_phone=\u00bb30px||||false|false\u00bb custom_padding_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/motelpedromontt.cl\/wp-content\/uploads\/2025\/02\/Untitled-design-2025-02-27T142413.544.png\u00bb title_text=\u00bbUntitled design &#8211; 2025-02-27T142413.544&#8243; align=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb4827deed-2a92-4d97-a22f-f01067ae6873&#8243; header_font=\u00bb||||||||\u00bb header_4_font=\u00bbManrope|700|||||||\u00bb header_4_text_color=\u00bb#000000&#8243; header_4_font_size=\u00bb36px\u00bb header_4_line_height=\u00bb1.4em\u00bb text_orientation=\u00bbcenter\u00bb custom_margin=\u00bb||0px||false|false\u00bb header_4_font_size_tablet=\u00bb16px\u00bb header_4_font_size_phone=\u00bb14px\u00bb header_4_font_size_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4>Con Jacuzzi<\/h4>\n<p>[\/et_pb_text][et_pb_button button_url=\u00bbhttps:\/\/motelpedromontt.cl\/index.php\/jacuzzi\/\u00bb button_text=\u00bbCon\u00f3zcalas\u00bb button_alignment=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbc9fe482c-2e2c-4f8c-9652-7702a242bc65&#8243; custom_button=\u00bbon\u00bb button_text_size=\u00bb14px\u00bb button_text_color=\u00bb#D37643&#8243; button_bg_color=\u00bbRGBA(255,255,255,0)\u00bb button_border_color=\u00bb#D37643&#8243; button_border_radius=\u00bb0px\u00bb button_font=\u00bbInter|700||on|||||\u00bb custom_padding=\u00bb16px|24px|16px|24px|true|true\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbFeatures\u00bb module_id=\u00bbservicios\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#FAF5EF\u00bb collapsed=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbb327cbe4-b1d5-4b66-ad37-40c8f2f061ba\u00bb header_2_font=\u00bbManrope|700|||||||\u00bb header_2_text_color=\u00bb#000000&#8243; header_2_font_size=\u00bb48px\u00bb header_2_line_height=\u00bb1.2em\u00bb text_orientation=\u00bbcenter\u00bb header_2_font_size_tablet=\u00bb32px\u00bb header_2_font_size_phone=\u00bb20px\u00bb header_2_font_size_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>Servicios<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_4,1_4,1_4,1_4&#8243; custom_padding_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bbrgba(235,228,221,0.28)\u00bb custom_padding=\u00bb50px|50px||50px|false|true\u00bb custom_padding_tablet=\u00bb30px|30px||30px|false|true\u00bb custom_padding_phone=\u00bb20px|20px||20px|false|true\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/motelpedromontt.cl\/wp-content\/uploads\/2025\/02\/Untitled-design-2025-02-24T170347.318.png\u00bb title_text=\u00bbUntitled design &#8211; 2025-02-24T170347.318&#8243; align=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb47%\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb4827deed-2a92-4d97-a22f-f01067ae6873&#8243; header_font=\u00bb||||||||\u00bb header_4_font=\u00bbManrope|700|||||||\u00bb header_4_text_color=\u00bb#000000&#8243; header_4_font_size=\u00bb19px\u00bb header_4_line_height=\u00bb1.4em\u00bb text_orientation=\u00bbcenter\u00bb custom_margin=\u00bb||0px||false|false\u00bb header_4_font_size_tablet=\u00bb16px\u00bb header_4_font_size_phone=\u00bb14px\u00bb header_4_font_size_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4>TV Cable<\/h4>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/motelpedromontt.cl\/wp-content\/uploads\/2025\/02\/2.png\u00bb title_text=\u00bb2&#8243; align=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb47%\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb4827deed-2a92-4d97-a22f-f01067ae6873&#8243; header_font=\u00bb||||||||\u00bb header_4_font=\u00bbManrope|700|||||||\u00bb header_4_text_color=\u00bb#000000&#8243; header_4_font_size=\u00bb19px\u00bb header_4_line_height=\u00bb1.4em\u00bb text_orientation=\u00bbcenter\u00bb custom_margin=\u00bb||0px||false|false\u00bb header_4_font_size_tablet=\u00bb16px\u00bb header_4_font_size_phone=\u00bb14px\u00bb header_4_font_size_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4>Excelente Conectividad<\/h4>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb4c43b4b6-66bf-432d-959a-705bda24a650&#8243; text_font=\u00bbOpen Sans||||||||\u00bb text_text_color=\u00bb#666666&#8243; text_line_height=\u00bb1.8em\u00bb link_text_color=\u00bb#666666&#8243; text_orientation=\u00bbcenter\u00bb header_font_size_tablet=\u00bb55px\u00bb header_font_size_last_edited=\u00bboff|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Cercano a Maetro Franklin y Rondizzoni<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/motelpedromontt.cl\/wp-content\/uploads\/2025\/02\/3.png\u00bb title_text=\u00bb3&#8243; align=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb47%\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb4827deed-2a92-4d97-a22f-f01067ae6873&#8243; header_font=\u00bb||||||||\u00bb header_4_font=\u00bbManrope|700|||||||\u00bb header_4_text_color=\u00bb#000000&#8243; header_4_font_size=\u00bb19px\u00bb header_4_line_height=\u00bb1.4em\u00bb text_orientation=\u00bbcenter\u00bb custom_margin=\u00bb||0px||false|false\u00bb header_4_font_size_tablet=\u00bb16px\u00bb header_4_font_size_phone=\u00bb14px\u00bb header_4_font_size_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4>Servicio de Bar las 24 horas<\/h4>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/motelpedromontt.cl\/wp-content\/uploads\/2025\/02\/4.png\u00bb title_text=\u00bb4&#8243; align=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb47%\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb4827deed-2a92-4d97-a22f-f01067ae6873&#8243; header_font=\u00bb||||||||\u00bb header_4_font=\u00bbManrope|700|||||||\u00bb header_4_text_color=\u00bb#000000&#8243; header_4_font_size=\u00bb19px\u00bb header_4_line_height=\u00bb1.4em\u00bb text_orientation=\u00bbcenter\u00bb custom_margin=\u00bb||0px||false|false\u00bb header_4_font_size_tablet=\u00bb16px\u00bb header_4_font_size_phone=\u00bb14px\u00bb header_4_font_size_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4>Pisos Higienizados<\/h4>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_4,1_4,1_4,1_4&#8243; custom_padding_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bbrgba(235,228,221,0.28)\u00bb custom_padding=\u00bb|50px|50px|50px|false|true\u00bb custom_padding_tablet=\u00bb|30px|30px|30px|false|true\u00bb custom_padding_phone=\u00bb|20px|20px|20px|false|true\u00bb saved_tabs=\u00bball\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/motelpedromontt.cl\/wp-content\/uploads\/2025\/02\/5.png\u00bb title_text=\u00bb5&#8243; align=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb47%\u00bb custom_margin=\u00bb||10px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb4827deed-2a92-4d97-a22f-f01067ae6873&#8243; header_font=\u00bb||||||||\u00bb header_4_font=\u00bbManrope|700|||||||\u00bb header_4_text_color=\u00bb#000000&#8243; header_4_font_size=\u00bb19px\u00bb header_4_line_height=\u00bb1.4em\u00bb text_orientation=\u00bbcenter\u00bb custom_margin=\u00bb||0px||false|false\u00bb header_4_font_size_tablet=\u00bb16px\u00bb header_4_font_size_phone=\u00bb14px\u00bb header_4_font_size_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4>Toallas Desechables<\/h4>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/motelpedromontt.cl\/wp-content\/uploads\/2025\/02\/6.png\u00bb title_text=\u00bb6&#8243; align=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb47%\u00bb custom_margin=\u00bb||10px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb4827deed-2a92-4d97-a22f-f01067ae6873&#8243; header_font=\u00bb||||||||\u00bb header_4_font=\u00bbManrope|700|||||||\u00bb header_4_text_color=\u00bb#000000&#8243; header_4_font_size=\u00bb19px\u00bb header_4_line_height=\u00bb1.4em\u00bb text_orientation=\u00bbcenter\u00bb custom_margin=\u00bb||0px||false|false\u00bb header_4_font_size_tablet=\u00bb16px\u00bb header_4_font_size_phone=\u00bb14px\u00bb header_4_font_size_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4>Abierto las 24 horas<\/h4>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/motelpedromontt.cl\/wp-content\/uploads\/2025\/02\/7.png\u00bb title_text=\u00bb7&#8243; align=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb47%\u00bb custom_margin=\u00bb||10px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb4827deed-2a92-4d97-a22f-f01067ae6873&#8243; header_font=\u00bb||||||||\u00bb header_4_font=\u00bbManrope|700|||||||\u00bb header_4_text_color=\u00bb#000000&#8243; header_4_font_size=\u00bb19px\u00bb header_4_line_height=\u00bb1.4em\u00bb text_orientation=\u00bbcenter\u00bb custom_margin=\u00bb||0px||false|false\u00bb header_4_font_size_tablet=\u00bb16px\u00bb header_4_font_size_phone=\u00bb14px\u00bb header_4_font_size_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4>Privacidad<\/h4>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/motelpedromontt.cl\/wp-content\/uploads\/2025\/02\/8.png\u00bb title_text=\u00bb8&#8243; align=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb47%\u00bb custom_margin=\u00bb||10px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb4827deed-2a92-4d97-a22f-f01067ae6873&#8243; header_font=\u00bb||||||||\u00bb header_4_font=\u00bbManrope|700|||||||\u00bb header_4_text_color=\u00bb#000000&#8243; header_4_font_size=\u00bb19px\u00bb header_4_line_height=\u00bb1.4em\u00bb text_orientation=\u00bbcenter\u00bb custom_margin=\u00bb||0px||false|false\u00bb header_4_font_size_tablet=\u00bb16px\u00bb header_4_font_size_phone=\u00bb14px\u00bb header_4_font_size_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4>Estacionamiento a la Puerta de la Habitaci\u00f3n<\/h4>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_4,1_4,1_4,1_4&#8243; custom_padding_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bbrgba(235,228,221,0.28)\u00bb custom_padding=\u00bb|50px|50px|50px|false|true\u00bb custom_padding_tablet=\u00bb|30px|30px|30px|false|true\u00bb custom_padding_phone=\u00bb|20px|20px|20px|false|true\u00bb saved_tabs=\u00bball\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/motelpedromontt.cl\/wp-content\/uploads\/2025\/02\/9.png\u00bb title_text=\u00bb9&#8243; align=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb47%\u00bb custom_margin=\u00bb||10px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb4827deed-2a92-4d97-a22f-f01067ae6873&#8243; header_font=\u00bb||||||||\u00bb header_4_font=\u00bbManrope|700|||||||\u00bb header_4_text_color=\u00bb#000000&#8243; header_4_font_size=\u00bb19px\u00bb header_4_line_height=\u00bb1.4em\u00bb text_orientation=\u00bbcenter\u00bb custom_margin=\u00bb||0px||false|false\u00bb header_4_font_size_tablet=\u00bb16px\u00bb header_4_font_size_phone=\u00bb14px\u00bb header_4_font_size_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4>Cortes\u00eda de Bienvenida<\/h4>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/motelpedromontt.cl\/wp-content\/uploads\/2025\/02\/10.png\u00bb title_text=\u00bb10&#8243; align=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb47%\u00bb custom_margin=\u00bb||10px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bb4827deed-2a92-4d97-a22f-f01067ae6873&#8243; header_font=\u00bb||||||||\u00bb header_4_font=\u00bbManrope|700|||||||\u00bb header_4_text_color=\u00bb#000000&#8243; header_4_font_size=\u00bb19px\u00bb header_4_line_height=\u00bb1.4em\u00bb text_orientation=\u00bbcenter\u00bb custom_margin=\u00bb||0px||false|false\u00bb header_4_font_size_tablet=\u00bb16px\u00bb header_4_font_size_phone=\u00bb14px\u00bb header_4_font_size_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4>Decoraci\u00f3n Especial<\/h4>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/motelpedromontt.cl\/wp-content\/uploads\/2025\/02\/11.png\u00bb title_text=\u00bb11&#8243; align=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb47%\u00bb custom_margin=\u00bb||10px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb4827deed-2a92-4d97-a22f-f01067ae6873&#8243; header_font=\u00bb||||||||\u00bb header_4_font=\u00bbManrope|700|||||||\u00bb header_4_text_color=\u00bb#000000&#8243; header_4_font_size=\u00bb19px\u00bb header_4_line_height=\u00bb1.4em\u00bb text_orientation=\u00bbcenter\u00bb custom_margin=\u00bb||0px||false|false\u00bb header_4_font_size_tablet=\u00bb16px\u00bb header_4_font_size_phone=\u00bb14px\u00bb header_4_font_size_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4>Jacuzzi<\/h4>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; specialty=\u00bbon\u00bb admin_label=\u00bbPromos\u00bb module_id=\u00bbprecios\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#FAF5EF\u00bb collapsed=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; specialty_columns=\u00bb2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_row_inner _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb90%\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column_inner saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbb327cbe4-b1d5-4b66-ad37-40c8f2f061ba\u00bb header_2_font=\u00bbManrope|700|||||||\u00bb header_2_text_color=\u00bb#000000&#8243; header_2_font_size=\u00bb48px\u00bb header_2_line_height=\u00bb1.2em\u00bb header_2_font_size_tablet=\u00bb32px\u00bb header_2_font_size_phone=\u00bb20px\u00bb header_2_font_size_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>Precios<\/h2>\n<p>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbb327cbe4-b1d5-4b66-ad37-40c8f2f061ba\u00bb header_2_font=\u00bbManrope|700|||||||\u00bb header_2_text_color=\u00bb#D37643&#8243; header_2_font_size=\u00bb48px\u00bb header_2_line_height=\u00bb1.2em\u00bb custom_margin=\u00bb||0px||false|false\u00bb header_2_font_size_tablet=\u00bb32px\u00bb header_2_font_size_phone=\u00bb20px\u00bb header_2_font_size_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>$25.000<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb4827deed-2a92-4d97-a22f-f01067ae6873&#8243; header_font=\u00bb||||||||\u00bb header_4_font=\u00bbManrope|700|||||||\u00bb header_4_text_color=\u00bb#D37643&#8243; header_4_font_size=\u00bb19px\u00bb header_4_line_height=\u00bb1.4em\u00bb custom_margin=\u00bb||0px||false|false\u00bb header_4_font_size_tablet=\u00bb16px\u00bb header_4_font_size_phone=\u00bb14px\u00bb header_4_font_size_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4>Desde<\/h4>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbaaa7c440-590a-4078-ae0c-0f3c699ac51c\u00bb header_font=\u00bb||||||||\u00bb header_3_font=\u00bbManrope|700|||||||\u00bb header_3_text_color=\u00bb#008186&#8243; header_3_font_size=\u00bb25px\u00bb header_3_line_height=\u00bb1.4em\u00bb header_3_font_size_tablet=\u00bb20px\u00bb header_3_font_size_phone=\u00bb16px\u00bb header_3_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3>3 Horas<\/h3>\n<p>[\/et_pb_text][\/et_pb_column_inner][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column_inner saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_button button_url=\u00bbhttps:\/\/www.waze.com\/ul?ll=-33.4727562,-70.6520796&#038;navigate=yes\u00bb button_text=\u00bbver ruta en waze\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb31b4f027-aaa0-4f2f-ae02-959764e19e4f\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb14px\u00bb button_text_color=\u00bb#FFFFFF\u00bb button_bg_color=\u00bbrgba(0,0,0,0.65)\u00bb button_border_width=\u00bb0px\u00bb button_border_radius=\u00bb0px\u00bb button_font=\u00bbInter|700||on|||||\u00bb custom_padding=\u00bb16px|24px|16px|24px|true|true\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][et_pb_button button_url=\u00bbtel:+56233660015&#8243; button_text=\u00bbLlamar a Tel\u00e9fono fijo\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb31b4f027-aaa0-4f2f-ae02-959764e19e4f\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb14px\u00bb button_text_color=\u00bb#FFFFFF\u00bb button_bg_color=\u00bb#D37643&#8243; button_border_width=\u00bb0px\u00bb button_border_radius=\u00bb0px\u00bb button_font=\u00bbInter|700||on|||||\u00bb custom_padding=\u00bb16px|24px|16px|24px|true|true\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][et_pb_button button_url=\u00bbhttps:\/\/wa.me\/+56921703656&#8243; button_text=\u00bbEnviar Whatsapp\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb31b4f027-aaa0-4f2f-ae02-959764e19e4f\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb14px\u00bb button_text_color=\u00bb#FFFFFF\u00bb button_bg_color=\u00bb#008186&#8243; button_border_width=\u00bb0px\u00bb button_border_radius=\u00bb0px\u00bb button_font=\u00bbInter|700||on|||||\u00bb custom_padding=\u00bb16px|24px|16px|24px|true|true\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_image src=\u00bbhttps:\/\/motelpedromontt.cl\/wp-content\/uploads\/2025\/02\/2-1.png\u00bb title_text=\u00bb2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb70%\u00bb custom_margin=\u00bb|||-15%|false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_image src=\u00bbhttps:\/\/motelpedromontt.cl\/wp-content\/uploads\/2025\/02\/1.png\u00bb title_text=\u00bb1&#8243; align=\u00bbright\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb80%\u00bb custom_margin=\u00bb-25%||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; disabled_on=\u00bbon|on|on\u00bb admin_label=\u00bbTestimonial\u00bb _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#FAF5EF\u00bb custom_padding=\u00bb||10%||false|false\u00bb disabled=\u00bbon\u00bb collapsed=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb1_4,3_4&#8243; custom_padding_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb50px|50px|50px|50px|true|true\u00bb custom_padding_tablet=\u00bb30px|30px|30px|30px|true|true\u00bb custom_padding_phone=\u00bb20px|20px|20px|20px|true|true\u00bb box_shadow_style=\u00bbpreset1&#8243; box_shadow_vertical=\u00bb20px\u00bb box_shadow_blur=\u00bb50px\u00bb box_shadow_color=\u00bbrgba(63,22,0,0.2)\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_icon font_icon=\u00bb&#xf10d;||fa||900&#8243; icon_color=\u00bb#008186&#8243; icon_width=\u00bb130px\u00bb align=\u00bbright\u00bb align_tablet=\u00bbleft\u00bb align_phone=\u00bbleft\u00bb align_last_edited=\u00bbon|tablet\u00bb _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_icon][\/et_pb_column][et_pb_column type=\u00bb3_4&#8243; _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbb327cbe4-b1d5-4b66-ad37-40c8f2f061ba\u00bb header_2_font=\u00bbManrope|700|||||||\u00bb header_2_text_color=\u00bb#000000&#8243; header_2_font_size=\u00bb48px\u00bb header_2_line_height=\u00bb1.2em\u00bb header_2_font_size_tablet=\u00bb32px\u00bb header_2_font_size_phone=\u00bb20px\u00bb header_2_font_size_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>\u201cNisl massa, ultrices vitae ornare sit amet, ultricies eget orci. Sed vitae nulla et justo pellentesque congue nec eu risus.\u201d<\/h2>\n<p>[\/et_pb_text][et_pb_blurb title=\u00bbRenesmee Thomas\u00bb image=\u00bbhttps:\/\/motelpedromontt.cl\/wp-content\/uploads\/2025\/02\/portrait-square-08.jpg\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb60px\u00bb content_max_width=\u00bb100%\u00bb _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbf2eb1c46-6ab3-4c5f-a14c-7deb82368558&#8243; header_font=\u00bbManrope|700|||||||\u00bb header_text_color=\u00bb#000000&#8243; header_font_size=\u00bb19px\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbOpen Sans||||||||\u00bb body_text_color=\u00bb#666666&#8243; body_line_height=\u00bb1.6em\u00bb animation=\u00bboff\u00bb header_font_size_tablet=\u00bb16px\u00bb header_font_size_phone=\u00bb15px\u00bb header_font_size_last_edited=\u00bbon|phone\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Product Solutions Liason, Pen Family<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbFeatures\u00bb module_id=\u00bbubicacion\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#FAF5EF\u00bb collapsed=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbb327cbe4-b1d5-4b66-ad37-40c8f2f061ba\u00bb header_2_font=\u00bbManrope|700|||||||\u00bb header_2_text_color=\u00bb#000000&#8243; header_2_font_size=\u00bb48px\u00bb header_2_line_height=\u00bb1.2em\u00bb text_orientation=\u00bbcenter\u00bb header_2_font_size_tablet=\u00bb32px\u00bb header_2_font_size_phone=\u00bb20px\u00bb header_2_font_size_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>Ubicaci\u00f3n<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_code _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<iframe src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d3328.0996524655716!2d-70.65207959810533!3d-33.47275620401504!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x9662c53c1a4d765d%3A0x4719d2f2ba0ef0f2!2sAv.%20Pedro%20Montt%201379%2C%208361161%20Santiago%2C%20Regi%C3%B3n%20Metropolitana!5e0!3m2!1ses!2scl!4v1740677368115!5m2!1ses!2scl\" width=\"600\" height=\"450\" style=\"border:0;\" allowfullscreen=\"\" loading=\"lazy\" referrerpolicy=\"no-referrer-when-downgrade\"><\/iframe>[\/et_pb_code][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb title=\u00bbAvenida Pedro Montt 1379, Santiago\u00bb url=\u00bbhttps:\/\/maps.app.goo.gl\/a85rnc1J8aqyJkFr5&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xf3c5;||fa||900&#8243; icon_color=\u00bb#008186&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb86px\u00bb content_max_width=\u00bb100%\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbb62950b2-9f88-417a-a624-825d61ec2a3d\u00bb header_font=\u00bbManrope|700||on|||||\u00bb header_text_color=\u00bb#D37643&#8243; header_font_size=\u00bb31px\u00bb header_letter_spacing=\u00bb1px\u00bb header_line_height=\u00bb1.4em\u00bb body_font_size=\u00bb25px\u00bb animation=\u00bboff\u00bb link_option_url=\u00bbhttps:\/\/maps.app.goo.gl\/a85rnc1J8aqyJkFr5&#8243; locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Cercano a Metro Rondizzoni, Franklin y Autopista Central<\/p>\n<p>[\/et_pb_blurb][et_pb_button button_url=\u00bbhttps:\/\/www.waze.com\/ul?ll=-33.4727562,-70.6520796&#038;navigate=yes\u00bb button_text=\u00bbver ruta en waze\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb31b4f027-aaa0-4f2f-ae02-959764e19e4f\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb14px\u00bb button_text_color=\u00bb#FFFFFF\u00bb button_bg_color=\u00bbrgba(0,0,0,0.65)\u00bb button_border_width=\u00bb0px\u00bb button_border_radius=\u00bb0px\u00bb button_font=\u00bbInter|700||on|||||\u00bb custom_padding=\u00bb16px|24px|16px|24px|true|true\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbContact Info\u00bb module_id=\u00bbcontacto\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#FAF5EF\u00bb locked=\u00bboff\u00bb collapsed=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb3_5,2_5&#8243; _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb3_5&#8243; _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb10%||||false|false\u00bb custom_padding_tablet=\u00bb0%||||false|false\u00bb custom_padding_phone=\u00bb0%||||false|false\u00bb custom_padding_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbe6504a1b-67eb-4b3d-b023-bcab277610b6&#8243; header_4_font=\u00bbManrope|700||on|||||\u00bb header_4_text_color=\u00bb#000000&#8243; header_4_font_size=\u00bb14px\u00bb header_4_letter_spacing=\u00bb1px\u00bb header_4_line_height=\u00bb1.4em\u00bb custom_margin=\u00bb||0px||false|false\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4>CONT\u00c1CTENOS<\/h4>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbb327cbe4-b1d5-4b66-ad37-40c8f2f061ba\u00bb header_2_font=\u00bbManrope|700|||||||\u00bb header_2_text_color=\u00bb#008186&#8243; header_2_font_size=\u00bb48px\u00bb header_2_line_height=\u00bb1.2em\u00bb custom_margin=\u00bb||10px||false|false\u00bb link_option_url=\u00bbhttps:\/\/wa.link\/lvkij2&#8243; link_option_url_new_window=\u00bbon\u00bb header_2_font_size_tablet=\u00bb32px\u00bb header_2_font_size_phone=\u00bb20px\u00bb header_2_font_size_last_edited=\u00bbon|desktop\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>Whatsapp: +56921703656<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbb327cbe4-b1d5-4b66-ad37-40c8f2f061ba\u00bb header_2_font=\u00bbManrope|700|||||||\u00bb header_2_text_color=\u00bb#D37643&#8243; header_2_font_size=\u00bb48px\u00bb header_2_line_height=\u00bb1.2em\u00bb link_option_url=\u00bbtel:+56233660015&#8243; header_2_font_size_tablet=\u00bb32px\u00bb header_2_font_size_phone=\u00bb20px\u00bb header_2_font_size_last_edited=\u00bbon|desktop\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>Tel\u00e9fono Fijo: +56233660015<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb2_5&#8243; _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/motelpedromontt.cl\/wp-content\/uploads\/2025\/02\/S7A5261.jpg\u00bb title_text=\u00bb_S7A5261&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbFooter\u00bb _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#FAF5EF\u00bb custom_padding=\u00bb||82px||false|false\u00bb collapsed=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb1_5,1_5,1_5,1_5,1_5&#8243; _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_5&#8243; _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/motelpedromontt.cl\/wp-content\/uploads\/2025\/03\/logo-motel-pedro-montt-600-x-170-px-1.png\u00bb title_text=\u00bblogo motel pedro montt (600 x 170 px) (1)\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb100%\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_5&#8243; _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb4827deed-2a92-4d97-a22f-f01067ae6873&#8243; header_font=\u00bb||||||||\u00bb header_4_font=\u00bbManrope|700|||||||\u00bb header_4_text_color=\u00bb#000000&#8243; header_4_font_size=\u00bb19px\u00bb header_4_line_height=\u00bb1.4em\u00bb custom_margin=\u00bb||20px||false|false\u00bb header_4_font_size_tablet=\u00bb16px\u00bb header_4_font_size_phone=\u00bb14px\u00bb header_4_font_size_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4>Habitaciones<\/h4>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb1f09816e-184e-4ce5-a4cf-b39c52c423ca\u00bb text_font=\u00bbOpen Sans||||||||\u00bb text_text_color=\u00bb#666666&#8243; text_font_size=\u00bb16px\u00bb text_line_height=\u00bb1.8em\u00bb link_text_color=\u00bb#666666&#8243; custom_margin=\u00bb||10px||false|false\u00bb text_font_size_tablet=\u00bb15px\u00bb text_font_size_phone=\u00bb14px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb header_font_size_tablet=\u00bb55px\u00bb header_font_size_last_edited=\u00bboff|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Cl\u00e1sicas<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb1f09816e-184e-4ce5-a4cf-b39c52c423ca\u00bb text_font=\u00bbOpen Sans||||||||\u00bb text_text_color=\u00bb#666666&#8243; text_font_size=\u00bb16px\u00bb text_line_height=\u00bb1.8em\u00bb link_text_color=\u00bb#666666&#8243; custom_margin=\u00bb||10px||false|false\u00bb text_font_size_tablet=\u00bb15px\u00bb text_font_size_phone=\u00bb14px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb header_font_size_tablet=\u00bb55px\u00bb header_font_size_last_edited=\u00bboff|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Con Jacuzzi<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_5&#8243; _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb4827deed-2a92-4d97-a22f-f01067ae6873&#8243; header_font=\u00bb||||||||\u00bb header_4_font=\u00bbManrope|700|||||||\u00bb header_4_text_color=\u00bb#000000&#8243; header_4_font_size=\u00bb19px\u00bb header_4_line_height=\u00bb1.4em\u00bb custom_margin=\u00bb||20px||false|false\u00bb header_4_font_size_tablet=\u00bb16px\u00bb header_4_font_size_phone=\u00bb14px\u00bb header_4_font_size_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4>Precios<\/h4>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb1f09816e-184e-4ce5-a4cf-b39c52c423ca\u00bb text_font=\u00bbOpen Sans||||||||\u00bb text_text_color=\u00bb#666666&#8243; text_font_size=\u00bb16px\u00bb text_line_height=\u00bb1.8em\u00bb link_text_color=\u00bb#666666&#8243; custom_margin=\u00bb||10px||false|false\u00bb text_font_size_tablet=\u00bb15px\u00bb text_font_size_phone=\u00bb14px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb header_font_size_tablet=\u00bb55px\u00bb header_font_size_last_edited=\u00bboff|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Desde $25.000 las 3 Horas<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_5&#8243; _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb4827deed-2a92-4d97-a22f-f01067ae6873&#8243; header_font=\u00bb||||||||\u00bb header_4_font=\u00bbManrope|700|||||||\u00bb header_4_text_color=\u00bb#000000&#8243; header_4_font_size=\u00bb19px\u00bb header_4_line_height=\u00bb1.4em\u00bb custom_margin=\u00bb||20px||false|false\u00bb header_4_font_size_tablet=\u00bb16px\u00bb header_4_font_size_phone=\u00bb14px\u00bb header_4_font_size_last_edited=\u00bbon|tablet\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4>Contacto<\/h4>\n<p>[\/et_pb_text][et_pb_blurb title=\u00bb+56233660015&#8243; url=\u00bbtel:+56233660015&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xf879;||fa||900&#8243; icon_color=\u00bb#008186&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb24px\u00bb content_max_width=\u00bb100%\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbb62950b2-9f88-417a-a624-825d61ec2a3d\u00bb header_font=\u00bbManrope|700||on|||||\u00bb header_text_color=\u00bb#D37643&#8243; header_font_size=\u00bb14px\u00bb header_letter_spacing=\u00bb1px\u00bb header_line_height=\u00bb1.4em\u00bb animation=\u00bboff\u00bb link_option_url=\u00bbtel:+56233660015&#8243; locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bb+56 9 21703656&#8243; url=\u00bbhttps:\/\/wa.me\/+56921703656&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xf232;||fa||400&#8243; icon_color=\u00bb#008186&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb24px\u00bb content_max_width=\u00bb100%\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbb62950b2-9f88-417a-a624-825d61ec2a3d\u00bb header_font=\u00bbManrope|700||on|||||\u00bb header_text_color=\u00bb#D37643&#8243; header_font_size=\u00bb14px\u00bb header_letter_spacing=\u00bb1px\u00bb header_line_height=\u00bb1.4em\u00bb animation=\u00bboff\u00bb link_option_url=\u00bbhttps:\/\/wa.me\/+56921703656&#8243; locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_5&#8243; _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb4827deed-2a92-4d97-a22f-f01067ae6873&#8243; header_font=\u00bb||||||||\u00bb header_4_font=\u00bbManrope|700|||||||\u00bb header_4_text_color=\u00bb#000000&#8243; header_4_font_size=\u00bb19px\u00bb header_4_line_height=\u00bb1.4em\u00bb custom_margin=\u00bb||10px||false|false\u00bb header_4_font_size_tablet=\u00bb16px\u00bb header_4_font_size_phone=\u00bb14px\u00bb header_4_font_size_last_edited=\u00bbon|tablet\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4>Nuestras Redes<\/h4>\n<p>[\/et_pb_text][et_pb_social_media_follow icon_color=\u00bb#D37643&#8243; use_icon_font_size=\u00bbon\u00bb icon_font_size=\u00bb20px\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_social_media_follow_network social_network=\u00bbfacebook\u00bb url=\u00bbhttps:\/\/www.facebook.com\/share\/1EBxjypHyb\/?mibextid=wwXIfr\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb follow_button=\u00bboff\u00bb url_new_window=\u00bbon\u00bb]facebook[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=\u00bbinstagram\u00bb url=\u00bbhttps:\/\/www.instagram.com\/motelpedromontt?igsh=cnRyMXAzdzYyNDY1&#038;utm_source=qr\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb follow_button=\u00bboff\u00bb url_new_window=\u00bbon\u00bb]instagram[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=\u00bbtiktok\u00bb url=\u00bbhttps:\/\/www.tiktok.com\/@motelpedromontt\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb background_enable_color=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb follow_button=\u00bboff\u00bb url_new_window=\u00bbon\u00bb]tiktok[\/et_pb_social_media_follow_network][\/et_pb_social_media_follow][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Descubra MOTEL PEDRO MONTTAbierto las 24 horas todos los d\u00edas del a\u00f1oCercano a Metro Rondizzoni, Franklin y Autopista CentralTel\u00e9fono FijoWhatsAppTipos de HabitacionesCl\u00e1sicasCon JacuzziServiciosTV CableExcelente ConectividadCercano a Maetro Franklin y RondizzoniServicio de Bar las 24 horasPisos HigienizadosToallas DesechablesAbierto las 24 horasPrivacidadEstacionamiento a la Puerta de la Habitaci\u00f3nCortes\u00eda de BienvenidaDecoraci\u00f3n EspecialJacuzziPrecios$25.000Desde3 Horas\u201cNisl massa, ultrices vitae ornare sit [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-8","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/motelpedromontt.cl\/index.php\/wp-json\/wp\/v2\/pages\/8","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/motelpedromontt.cl\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/motelpedromontt.cl\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/motelpedromontt.cl\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/motelpedromontt.cl\/index.php\/wp-json\/wp\/v2\/comments?post=8"}],"version-history":[{"count":42,"href":"https:\/\/motelpedromontt.cl\/index.php\/wp-json\/wp\/v2\/pages\/8\/revisions"}],"predecessor-version":[{"id":201,"href":"https:\/\/motelpedromontt.cl\/index.php\/wp-json\/wp\/v2\/pages\/8\/revisions\/201"}],"wp:attachment":[{"href":"https:\/\/motelpedromontt.cl\/index.php\/wp-json\/wp\/v2\/media?parent=8"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}